{"id":91913,"date":"2025-12-19T12:10:22","date_gmt":"2025-12-19T10:10:22","guid":{"rendered":"https:\/\/www.nus.agency\/?post_type=masters-y-postgrados&#038;p=91913"},"modified":"2026-03-23T17:11:41","modified_gmt":"2026-03-23T15:11:41","slug":"mba-direccion-gestion-empresas-salud","status":"publish","type":"masters-y-postgrados","link":"https:\/\/www.nus.agency\/es\/masters-y-postgrados\/mba-direccion-gestion-empresas-salud","title":{"rendered":"MBA en Direcci\u00f3n y Gesti\u00f3n de Empresas de Salud"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"91913\" class=\"elementor elementor-91913\" data-elementor-post-type=\"masters-y-postgrados\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dd1c521 elementor-section-stretched elementor-section-full_width elementor-section-content-top elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"dd1c521\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-20afb39\" data-id=\"20afb39\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c47a7e9 elementor-widget__width-inherit elementor-widget elementor-widget-image\" data-id=\"c47a7e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"774\" height=\"800\" src=\"https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/12\/master_mba_nus_agency.webp\" class=\"attachment-full size-full wp-image-91916\" alt=\"MBA en Direcci\u00f3n y Gesti\u00f3n de Empresas de Salud de NUS Agency\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-136e1f9\" data-id=\"136e1f9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-05e059b elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"05e059b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ce22c77\" data-id=\"ce22c77\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fc932b8 elementor-widget elementor-widget-image\" data-id=\"fc932b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"150\" src=\"https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/08\/logo-nus-k.png\" class=\"attachment-large size-large wp-image-90569\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e563b42\" data-id=\"e563b42\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-420e3c6 elementor-widget elementor-widget-image\" data-id=\"420e3c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"150\" src=\"https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/08\/logo-utamed-k.png\" class=\"attachment-full size-full wp-image-90570\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-64e1d89 elementor-hidden-desktop elementor-widget elementor-widget-image\" data-id=\"64e1d89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"301\" height=\"40\" src=\"https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/11\/nus_utamed_logos.webp\" class=\"attachment-large size-large wp-image-91602\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b3eeb94 elementor-widget__width-auto elementor-widget elementor-widget-text-editor\" data-id=\"b3eeb94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\/ M\u00c1STER DE FORMACI\u00d3N PERMANENTE\u00a0\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4722d3a elementor-widget elementor-widget-heading\" data-id=\"4722d3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">MBA en Direcci\u00f3n y Gesti\u00f3n de Empresas de Salud<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-100cb9d elementor-widget elementor-widget-text-editor\" data-id=\"100cb9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Transforma tu futuro profesional en salud con un MBA pr\u00e1ctico, innovador e internacional.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-891e74b elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"891e74b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-913268c\" data-id=\"913268c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-647554a elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"647554a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/09\/Calendar.svg\" class=\"attachment-full size-full wp-image-90860\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Inicio: Septiembre 2026<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-6b6a210\" data-id=\"6b6a210\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8d550b7 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"8d550b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/09\/Training.svg\" class=\"attachment-full size-full wp-image-90866\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Modalidad Blended o Full Time<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-6736421\" data-id=\"6736421\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0b133c0 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"0b133c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/09\/Certificate.svg\" class=\"attachment-full size-full wp-image-90861\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Doble acreditaci\u00f3n<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-1481fab\" data-id=\"1481fab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9bc218c elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"9bc218c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/09\/Health-IT.svg\" class=\"attachment-full size-full wp-image-90864\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">60 cr\u00e9ditos ECTS<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-07020da\" data-id=\"07020da\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c1ad4a4 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"c1ad4a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/12\/globe.webp\" class=\"attachment-full size-full wp-image-91915\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Idioma Espa\u00f1ol o Ingl\u00e9s<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a76d294 elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a76d294\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d599931\" data-id=\"d599931\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4129f01 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"4129f01\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#form\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Solicita informaci\u00f3n<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ebfa011\" data-id=\"ebfa011\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fa7ef14 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"fa7ef14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/forms.zohopublic.com\/nusagency\/form\/SolicituddeAdmisinMBACast\/formperma\/viTLn5jsKfPZX3JhcRp4vNhXPx0TCUmR7-yzKh4GbOs\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Solicita admisi\u00f3n<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ccb2d96 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ccb2d96\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a146cbe\" data-id=\"a146cbe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f54da20 elementor-widget elementor-widget-heading\" data-id=\"f54da20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Un programa transformador para l\u00edderes que quieren ir m\u00e1s all\u00e1\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eeca20d elementor-widget elementor-widget-text-editor\" data-id=\"eeca20d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">El <\/span><b>MBA en Direcci\u00f3n y Gesti\u00f3n de Empresas de Salud<\/b><span style=\"font-weight: 400;\"> de NUS Agency es una experiencia acad\u00e9mica de alto impacto dise\u00f1ada para profesionales que desean <\/span><b>crecer, liderar y transformar<\/b><span style=\"font-weight: 400;\"> organizaciones sanitarias en un entorno global, digital y en constante evoluci\u00f3n.<\/span><\/p><p><b>Tres ventajas exclusivas que impulsan tu carrera en salud:<\/b><\/p><ul><li><b>Bootcamp internacional en Barcelona<\/b><span style=\"font-weight: 400;\"> con acceso directo a hospitales, empresas <\/span><b>healthtech<\/b><span style=\"font-weight: 400;\">, startups biotech y l\u00edderes del ecosistema sanitario europeo.<\/span><\/li><li><b>Mentoring y formaci\u00f3n aplicada<\/b><span style=\"font-weight: 400;\">, dise\u00f1ada para acelerar tu ascenso y mejorar tu capacidad de direcci\u00f3n en entornos sanitarios complejos.<\/span><\/li><li><b>Especializaci\u00f3n 100% en gesti\u00f3n de salud<\/b><span style=\"font-weight: 400;\">, con foco en <\/span><b>innovaci\u00f3n<\/b><span style=\"font-weight: 400;\">, <\/span><b>salud digital<\/b><span style=\"font-weight: 400;\"> e <\/span><b>IA aplicada al sector sanitario<\/b><span style=\"font-weight: 400;\">.<\/span><\/li><li style=\"list-style-type: none;\">\u00a0<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d446804\" data-id=\"d446804\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-db39a39 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"db39a39\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-9778d42\" data-id=\"9778d42\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e23402 elementor-widget elementor-widget-heading\" data-id=\"6e23402\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Modalidad<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ffcd8a elementor-widget elementor-widget-text-editor\" data-id=\"2ffcd8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"white-space-collapse: preserve;\">Blended o Full time<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cb04745 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cb04745\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-a676da6\" data-id=\"a676da6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5264b67 elementor-widget elementor-widget-heading\" data-id=\"5264b67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Duraci\u00f3n<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4029b36 elementor-widget elementor-widget-text-editor\" data-id=\"4029b36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"white-space-collapse: preserve;\">12 meses<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e415f77 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e415f77\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-646e5da\" data-id=\"646e5da\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fda7baf elementor-widget elementor-widget-heading\" data-id=\"fda7baf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Inicio m\u00e1ster<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e2b058 elementor-widget elementor-widget-text-editor\" data-id=\"5e2b058\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Septiembre 2026, online<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cde44d8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cde44d8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-957cf32\" data-id=\"957cf32\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-19315a8 elementor-widget elementor-widget-heading\" data-id=\"19315a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Inicio Bootcamp<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6250ebd elementor-widget elementor-widget-text-editor\" data-id=\"6250ebd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Mayo 2027<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-eade73b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eade73b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-463101f\" data-id=\"463101f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ca3e1e elementor-widget elementor-widget-heading\" data-id=\"5ca3e1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Doble acreditaci\u00f3n<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06d4ca3 elementor-widget elementor-widget-text-editor\" data-id=\"06d4ca3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nus Agency + UTAMED<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-95eebe0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"95eebe0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ff3fa9f\" data-id=\"ff3fa9f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f0114e elementor-widget elementor-widget-heading\" data-id=\"1f0114e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Cr\u00e9ditos<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-845c08c elementor-widget elementor-widget-text-editor\" data-id=\"845c08c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>60 cr\u00e9ditos ECTS<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-95019f1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"95019f1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-a683a35\" data-id=\"a683a35\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ebd419b elementor-widget elementor-widget-heading\" data-id=\"ebd419b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Becas y Ayudas<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42e68c1 elementor-widget elementor-widget-text-editor\" data-id=\"42e68c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Consulta para acceder<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a4ea53d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a4ea53d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a025da8\" data-id=\"a025da8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37598cb elementor-widget elementor-widget-image\" data-id=\"37598cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"516\" height=\"616\" src=\"https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/12\/master_mic_nus_agency_perfil2.webp\" class=\"attachment-large size-large wp-image-95460\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-823ee0d\" data-id=\"823ee0d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ecb4f99 elementor-widget elementor-widget-heading\" data-id=\"ecb4f99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Enfoque internacional: una visi\u00f3n global para un sector global\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a196c8 elementor-widget elementor-widget-text-editor\" data-id=\"2a196c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">El sector salud opera en un entorno sin fronteras, y este MBA te prepara para liderar en \u00e9l. A trav\u00e9s de contenido global, experiencias multiculturales y un Bootcamp internacional en <\/span><b>Barcelona<\/b><span style=\"font-weight: 400;\">, conectar\u00e1s con uno de los ecosistemas de salud digital y biotech m\u00e1s din\u00e1micos de Europa.<\/span><\/p><p><b>Te permitir\u00e1:<\/b><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Comprender sistemas sanitarios y modelos de gesti\u00f3n internacionales<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Trabajar con profesores y profesionales con trayectoria global<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Integrarte en el ecosistema de innovaci\u00f3n en salud de Barcelona mediante visitas, talleres y proyectos reales<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-71a9a65 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"71a9a65\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5a3d0a8\" data-id=\"5a3d0a8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eaafad8 elementor-widget elementor-widget-heading\" data-id=\"eaafad8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfQu\u00e9 hace diferente a este MBA?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-63a3bbb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"63a3bbb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-55a0c2f\" data-id=\"55a0c2f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9266bf8 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"9266bf8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tLa experiencia inmersiva del Bootcamp internacional en Barcelona, donde vives el ecosistema m\u00e1s din\u00e1mico de salud digital en Europa.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-f2e5dfd\" data-id=\"f2e5dfd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a89cd65 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"a89cd65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-handshake\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tUn modelo de mentoring continuo, dise\u00f1ado para trasladar tus aprendizajes directamente a tu entorno profesional y acelerar tu desempe\u00f1o.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-f61e7f2\" data-id=\"f61e7f2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-61a15bb elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"61a15bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-hand-holding-medical\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tUna formaci\u00f3n profundamente orientada al futuro de la gesti\u00f3n sanitaria, con \u00e9nfasis en innovaci\u00f3n, IA, datos y transformaci\u00f3n digital.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7eee55f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7eee55f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0e21e98\" data-id=\"0e21e98\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-465922b elementor-widget elementor-widget-heading\" data-id=\"465922b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Plan de estudios del MBA<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-58fa2d8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"58fa2d8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-8c6fc3d\" data-id=\"8c6fc3d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-06b5f62 elementor-widget elementor-widget-text-editor\" data-id=\"06b5f62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>M\u00d3DULO 1<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77efd3a elementor-widget elementor-widget-heading\" data-id=\"77efd3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Direcci\u00f3n de Empresas<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1935fae elementor-widget elementor-widget-text-editor\" data-id=\"1935fae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Te proporciona las bases del management aplicado al sector salud: estrategia, finanzas, marketing, operaciones, liderazgo y emprendimiento. Aprender\u00e1s a tomar decisiones, dirigir equipos y gestionar organizaciones con visi\u00f3n empresarial.<\/span><\/p><p><b>15 ECTS<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-8e8d8d9\" data-id=\"8e8d8d9\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cd3d0b5 elementor-widget elementor-widget-text-editor\" data-id=\"cd3d0b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>M\u00d3DULO 2<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-877e3e6 elementor-widget elementor-widget-heading\" data-id=\"877e3e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Sector Salud<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-386e246 elementor-widget elementor-widget-text-editor\" data-id=\"386e246\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Profundiza en el funcionamiento del sistema sanitario: sistemas de salud globales, econom\u00eda, calidad, seguridad del paciente, tecnolog\u00eda, regulaci\u00f3n e innovaci\u00f3n cl\u00ednica. Obtendr\u00e1s una visi\u00f3n completa del entorno sanitario y sus desaf\u00edos. <\/span><b>\u00a0<\/b><\/p><p><b>18 ECTS<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-b03293b\" data-id=\"b03293b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d62a917 elementor-widget elementor-widget-text-editor\" data-id=\"d62a917\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>M\u00d3DULO 3<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b83c84e elementor-widget elementor-widget-heading\" data-id=\"b83c84e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Bootcamp de Emprendimiento en Salud<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e20e8fd elementor-widget elementor-widget-text-editor\" data-id=\"e20e8fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Tres semanas presenciales en Barcelona con talleres, visitas profesionales, coaching y proyectos reales de innovaci\u00f3n. Es una experiencia intensiva para desarrollar soluciones, modelos de negocio y capacidades emprendedoras en salud. <\/span><\/p><p><b>12 ECTS<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-c366a73\" data-id=\"c366a73\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-409b961 elementor-widget elementor-widget-text-editor\" data-id=\"409b961\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>M\u00d3DULO 4<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ebc3699 elementor-widget elementor-widget-heading\" data-id=\"ebc3699\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Trabajo Final de M\u00e1ster<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-412c54d elementor-widget elementor-widget-text-editor\" data-id=\"412c54d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Proyecto aplicado donde resuelves un reto real del sector salud. Guiado por un tutor, integrar\u00e1s todo lo aprendido y presentar\u00e1s tu propuesta ante un panel de expertos. <\/span><\/p><p><b>15 ECTS<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-b943f7b elementor-align-center elementor-widget elementor-widget-button\" data-id=\"b943f7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#form\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Solicita informaci\u00f3n<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-af81fb0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"af81fb0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5a814d9\" data-id=\"5a814d9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c7f5794 elementor-widget elementor-widget-heading\" data-id=\"c7f5794\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Claustro de Expertos que Lideran la Transformaci\u00f3n en Salud<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f198dde elementor-widget elementor-widget-text-editor\" data-id=\"f198dde\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Nuestro profesorado est\u00e1 formado por directivos y l\u00edderes del sector salud, con amplia experiencia en gesti\u00f3n e innovaci\u00f3n. Aprender\u00e1s de profesionales que transforman la salud, aplicando casos reales y decisiones estrat\u00e9gicas para impulsar tu desarrollo directivo con una visi\u00f3n global y pr\u00e1ctica.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8376d3e\" data-id=\"8376d3e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a165564 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"a165564\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/08\/nuria-saez-2.png\" class=\"attachment-full size-full wp-image-90344\" alt=\"\" srcset=\"https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/08\/nuria-saez-2.png 400w, https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/08\/nuria-saez-2-300x225.png 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-title\">N\u00faria S\u00e1ez<\/p><p class=\"elementor-image-box-description\">CEO de NUS Agency y Directora del MBA en Direcci\u00f3n y Gesti\u00f3n de Empresas de Salud. Enfermera, experta en innovaci\u00f3n y gesti\u00f3n educativa en salud.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-caeae08 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"caeae08\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-932831b\" data-id=\"932831b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f86149f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f86149f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-69f75f8\" data-id=\"69f75f8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1717c70 elementor-widget elementor-widget-heading\" data-id=\"1717c70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Formatos del MBA<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6160563\" data-id=\"6160563\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1dd40cd elementor-widget elementor-widget-text-editor\" data-id=\"1dd40cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">El MBA en Direcci\u00f3n y Gesti\u00f3n de Empresas de Salud de NUS Agency se adapta a las necesidades de profesionales con agendas exigentes. Por eso ofrecemos dos modalidades de estudio, ambas con el mismo nivel acad\u00e9mico, el mismo claustro y el mismo t\u00edtulo.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cef4f07 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cef4f07\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-39fcfcf\" data-id=\"39fcfcf\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2bfdaef elementor-widget elementor-widget-image\" data-id=\"2bfdaef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"572\" src=\"https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/12\/master_mba_nus_agency_blended.webp\" class=\"attachment-large size-large wp-image-91945\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-077e129 elementor-widget elementor-widget-heading\" data-id=\"077e129\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">MBA Full-Time en ingl\u00e9s<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad2126b elementor-widget elementor-widget-text-editor\" data-id=\"ad2126b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Experiencia inmersiva en Barcelona con enfoque internacional.<\/span><\/p><p><span style=\"font-weight: 400;\">Dise\u00f1ado para profesionales que buscan una experiencia transformadora e intensiva, con convivencia diaria, networking continuo y pr\u00e1ctica directiva presencial, impartido 100% en ingl\u00e9s.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-12c7eff elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"12c7eff\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-3c41c0d\" data-id=\"3c41c0d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bef1ecf elementor-position-top elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"bef1ecf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/12\/mappinline.webp\" class=\"attachment-full size-full wp-image-91929\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Clases presenciales semanales en Barcelona<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-699da23\" data-id=\"699da23\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-351e842 elementor-position-top elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"351e842\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/11\/health_it-black.webp\" class=\"attachment-full size-full wp-image-91761\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Acceso al Campus Virtual<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-d139822\" data-id=\"d139822\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39a29b2 elementor-position-top elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"39a29b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/09\/Training.svg\" class=\"attachment-full size-full wp-image-90866\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Smart Learning Full Time<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-9f15cd2\" data-id=\"9f15cd2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41901c5 elementor-position-top elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"41901c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/09\/Calendar.svg\" class=\"attachment-full size-full wp-image-90860\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Bootcamp de 3 semanas<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e803413\" data-id=\"e803413\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-61e5b1c elementor-widget elementor-widget-image\" data-id=\"61e5b1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"572\" src=\"https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/12\/master_mba_nus_agency_online.webp\" class=\"attachment-large size-large wp-image-91946\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29958af elementor-widget elementor-widget-heading\" data-id=\"29958af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">MBA Online (Blended) en castellano<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ede813 elementor-widget elementor-widget-text-editor\" data-id=\"5ede813\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Flexibilidad, acompa\u00f1amiento y experiencia internacional.<\/span><\/p><p><span style=\"font-weight: 400;\">El formato Online (Blended) est\u00e1 pensado para profesionales que necesitan combinar el MBA con un ritmo de vida exigente o que residen fuera de Espa\u00f1a, impartido completamente en castellano.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-007849f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"007849f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-b2ffd41\" data-id=\"b2ffd41\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc9974f elementor-position-top elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"cc9974f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/12\/mappinline.webp\" class=\"attachment-full size-full wp-image-91929\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Clases 100% online<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-96cae7d\" data-id=\"96cae7d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-32fe22d elementor-position-top elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"32fe22d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/11\/health_it-black.webp\" class=\"attachment-full size-full wp-image-91761\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Campus Virtual 24\/7<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-ba6eb23\" data-id=\"ba6eb23\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22ad7f6 elementor-position-top elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"22ad7f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/09\/Training.svg\" class=\"attachment-full size-full wp-image-90866\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Smart Learning Digital<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-c799cd1\" data-id=\"c799cd1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43bfb94 elementor-position-top elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"43bfb94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/09\/Calendar.svg\" class=\"attachment-full size-full wp-image-90860\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Bootcamp de 3 semanas en Barcelona<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bc5189b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bc5189b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a9021f2\" data-id=\"a9021f2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cb4b98f elementor-widget elementor-widget-heading\" data-id=\"cb4b98f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Perfil del participante<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23de64c elementor-widget elementor-widget-text-editor\" data-id=\"23de64c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Como estudiante del<\/span><b>\u00a0MBA en Direcci\u00f3n y Gesti\u00f3n de Empresas de Salud<\/b><span style=\"font-weight: 400;\">, te unir\u00e1s a un grupo de profesionales con experiencia que buscan avanzar en sus carreras. Compartir\u00e1s el aula con un colectivo diverso de <\/span><b>emprendedores, empresarios, directores generales y mandos intermedios<\/b><span style=\"font-weight: 400;\">, procedentes de distintos sectores y con un s\u00f3lido bagaje acad\u00e9mico.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb7ff51 elementor-widget elementor-widget-heading\" data-id=\"fb7ff51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Perfiles internacionales e interculturales que enriquecen la experiencia<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6eb9a70 elementor-widget elementor-widget-text-editor\" data-id=\"6eb9a70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">El MBA re\u00fane a profesionales del \u00e1mbito sanitario \u2014m\u00e9dicos, enfermeras, farmac\u00e9uticos y gestores cl\u00ednicos\u2014 junto a perfiles de negocios, ingenier\u00eda, derecho, econom\u00eda y recursos humanos. Se espera una comunidad diversa procedente de Am\u00e9rica, Europa, \u00c1frica y Asia, cuya combinaci\u00f3n de experiencias y trayectorias enriquecer\u00e1 el aprendizaje y potenciar\u00e1 el networking en un entorno internacional.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f31572c\" data-id=\"f31572c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a41409 elementor-widget elementor-widget-image\" data-id=\"7a41409\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"516\" height=\"616\" src=\"https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/12\/master_mic_nus_agency_perfil.webp\" class=\"attachment-large size-large wp-image-91947\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6d4ee02 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6d4ee02\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-266bf7a\" data-id=\"266bf7a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-309c32f elementor-widget elementor-widget-heading\" data-id=\"309c32f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">3 beneficios dise\u00f1ados para los perfiles m\u00e1s destacados<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-18bf781 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"18bf781\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-36d7783\" data-id=\"36d7783\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-436baed elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"436baed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tLa vivencia del Bootcamp internacional en Barcelona, un acelerador de visi\u00f3n estrat\u00e9gica en organizaciones sanitarias globales.\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-25608ca\" data-id=\"25608ca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f5fc47 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"5f5fc47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-handshake\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tUn enfoque formativo acompa\u00f1ado de mentores y directivos expertos, que permite avanzar m\u00e1s r\u00e1pido hacia posiciones de liderazgo.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-79bbce0\" data-id=\"79bbce0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ef8487 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"1ef8487\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-hand-holding-medical\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tUna formaci\u00f3n centrada en salud digital, innovaci\u00f3n y IA, clave para profesionales con ambici\u00f3n de crecimiento y promoci\u00f3n directiva.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-175a234 elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"175a234\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4c08473\" data-id=\"4c08473\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-cc1e312\" data-id=\"cc1e312\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34df71d elementor-widget elementor-widget-heading\" data-id=\"34df71d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Salidas profesionales\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4559c37 elementor-widget elementor-widget-text-editor\" data-id=\"4559c37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">El <\/span><b>MBA en Direcci\u00f3n y Gesti\u00f3n de Empresas de Salud<\/b><span style=\"font-weight: 400;\"> te prepara para asumir posiciones de liderazgo en organizaciones sanitarias, combinando conocimientos en <\/span><b>gesti\u00f3n, estrategia y liderazgo<\/b><span style=\"font-weight: 400;\"> aplicados al sector salud. Adquirir\u00e1s las habilidades necesarias para dirigir equipos, gestionar recursos y tomar decisiones estrat\u00e9gicas en entornos complejos.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b072a98 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"b072a98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#form\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Solicita informaci\u00f3n<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ad1c358 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ad1c358\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b1fd04a\" data-id=\"b1fd04a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-bee4077 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bee4077\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1c48f2c\" data-id=\"1c48f2c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-405b805 elementor-widget elementor-widget-heading\" data-id=\"405b805\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Admisiones<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6703d10 elementor-widget elementor-widget-text-editor\" data-id=\"6703d10\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">El proceso de admisi\u00f3n eval\u00faa tu potencial directivo y tu motivaci\u00f3n para crecer en el sector salud. Cada candidatura se revisa de forma individual, y el equipo de Admisiones te acompa\u00f1a durante toda la evaluaci\u00f3n y validaci\u00f3n de requisitos en un proceso \u00e1gil, confidencial y orientado a identificar tu proyecci\u00f3n como futuro l\u00edder.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b43ce1e elementor-widget elementor-widget-toggle\" data-id=\"b43ce1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-1881\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1881\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Requisitos y documentaci\u00f3n de admisi\u00f3n<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1881\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1881\"><p><span style=\"font-weight: 400;\">Para postularte al programa en las dos modalidades, debes cumplir los siguientes criterios:<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Titulaci\u00f3n universitaria oficial <\/b><span style=\"font-weight: 400;\">(debe estar debidamente apostillada por la Haya).<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Curr\u00edculum Vitae<\/b><span style=\"font-weight: 400;\"> actualizado<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Carta de motivaci\u00f3n<\/b><span style=\"font-weight: 400;\"> explicando los motivos para cursar el m\u00e1ster<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Carta de apoyo<\/b><span style=\"font-weight: 400;\"> de la empresa o de un directivo\u00a0<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Fotocopia del DNI o pasaporte<\/b><\/li><\/ul><p><span style=\"font-weight: 400;\">M\u00e1s informaci\u00f3n sobre la apostilla de tu titulaci\u00f3n universitaria oficial, en el<\/span><b><a href=\"https:\/\/www.nus.agency\/es\/admisiones-preguntas-frecuentes\" target=\"_blank\" rel=\"noopener\"> siguiente enlace<\/a>.<\/b><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-1882\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1882\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Requisitos de idioma<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1882\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1882\"><p><b>MBA Online Blended en castellano:<\/b><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Estudiantes de pa\u00edses hispanohablantes: <\/span><i><span style=\"font-weight: 400;\">no se requiere certificado<\/span><\/i><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Estudiantes de pa\u00edses no hispanohablantes: <\/span><i><span style=\"font-weight: 400;\">certificado oficial de espa\u00f1ol<\/span><\/i><\/li><\/ul><ul><li style=\"font-weight: 400;\" aria-level=\"3\"><b>DELE<\/b><span style=\"font-weight: 400;\"> (Diplomas de Espa\u00f1ol como Lengua Extranjera, v\u00e1lidos de por vida seg\u00fan nivel)<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"3\"><b>SIELE<\/b><span style=\"font-weight: 400;\"> (Servicio Internacional de Evaluaci\u00f3n de la Lengua Espa\u00f1ola, digital y flexible).<\/span><\/li><\/ul><p><b>MBA Full Time en ingl\u00e9s:<\/b><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Certificado oficial de ingl\u00e9s<\/b><span style=\"font-weight: 400;\"> con antig\u00fcedad m\u00e1xima de 2 a\u00f1os y puntuaciones m\u00ednimas aceptadas: TOEFL: 95 \/ TOEIC: 850 \/ IELTS: 6.5 \/ CAE: C \/ Duolingo English Test: +130.<\/span><\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c594ba2\" data-id=\"c594ba2\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aaef837 elementor-widget elementor-widget-image\" data-id=\"aaef837\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"447\" src=\"https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/12\/master_mba_nus_agency_admisiones.webp\" class=\"attachment-large size-large wp-image-91951\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-91c6cda elementor-widget elementor-widget-text-editor\" data-id=\"91c6cda\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ser admitido en este MBA te permitir\u00e1 acceder a ventajas \u00fanicas como:<\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Participar en el <\/span><b>Bootcamp internacional en Barcelona<\/b><span style=\"font-weight: 400;\">, una experiencia que transforma tu perfil profesional.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Integrarte en un programa con <\/span><b>mentores expertos<\/b><span style=\"font-weight: 400;\"> que guiar\u00e1n tu desarrollo directivo.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Formarte en competencias de alta demanda: <\/span><b>innovaci\u00f3n<\/b><span style=\"font-weight: 400;\">, <\/span><b>salud digital<\/b><span style=\"font-weight: 400;\">, <\/span><b>IA<\/b><span style=\"font-weight: 400;\"> y liderazgo sanitario.<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8f7eced elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8f7eced\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ecd851b\" data-id=\"ecd851b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-24d1f1f elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"24d1f1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/09\/Exam-Multiple-Choice.svg\" class=\"attachment-full size-full wp-image-90863\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ee667d elementor-widget elementor-widget-heading\" data-id=\"8ee667d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Entrega de documentaci\u00f3n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f4de89 elementor-widget elementor-widget-text-editor\" data-id=\"2f4de89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Toda la documentaci\u00f3n debe subirse a trav\u00e9s del siguiente enlace de admisi\u00f3n para completar la candidatura y que sea evaluada por el Comit\u00e9 de Admisiones.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6581e38\" data-id=\"6581e38\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ffc29a6 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"ffc29a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/12\/arrowsquareupright.webp\" class=\"attachment-full size-full wp-image-91948\" alt=\"\" srcset=\"https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/12\/arrowsquareupright.webp 200w, https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/12\/elementor\/thumbs\/arrowsquareupright-rg1un6y3r1z6it0e14z1a2k7fck8lm5kxz132aejdc.webp 40w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-159a9ab elementor-widget elementor-widget-heading\" data-id=\"159a9ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Proceso de admisi\u00f3n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1b8952 elementor-widget elementor-widget-text-editor\" data-id=\"e1b8952\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tu candidatura ser\u00e1 evaluada por el <strong>Comit\u00e9 de Admisiones<\/strong>, compuesto por miembros del profesorado y del equipo de Direcci\u00f3n y Admisiones.<\/p><p>Durante el proceso, se valorar\u00e1 tu motivaci\u00f3n y trayectoria profesional.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-101f14f\" data-id=\"101f14f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-487d4c5 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"487d4c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/12\/usersfour.webp\" class=\"attachment-full size-full wp-image-91950\" alt=\"\" srcset=\"https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/12\/usersfour.webp 200w, https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/12\/elementor\/thumbs\/usersfour-rg1uncl4w26wggs747esp14yznsfvsryyqxzxy66c0.webp 40w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e88480e elementor-widget elementor-widget-heading\" data-id=\"e88480e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Compromiso con la igualdad\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eea48c2 elementor-widget elementor-widget-text-editor\" data-id=\"eea48c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>NUS garantiza la <strong>igualdad de oportunidades<\/strong> para todos los candidatos. No se discrimina por motivos de raza, color, religi\u00f3n, g\u00e9nero, orientaci\u00f3n sexual, nacionalidad o etnia, edad, estado civil, creencias pol\u00edticas, discapacidad o cualquier otro factor que impida una evaluaci\u00f3n justa de tu candidatura.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2c354a9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c354a9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1a9006b\" data-id=\"1a9006b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77b74a8 elementor-widget elementor-widget-heading\" data-id=\"77b74a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Precio, Becas y financiaci\u00f3n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a1f2419 elementor-widget elementor-widget-text-editor\" data-id=\"a1f2419\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Invertir en este MBA es apostar por tu crecimiento, tu confianza y tu futuro en el sector salud. Contamos con becas que impulsan el talento y alternativas de financiaci\u00f3n que facilitan el camino, porque creemos que las oportunidades deben estar al alcance de quienes desean avanzar. Tu desarrollo directivo empieza con una decisi\u00f3n: elegir formarte para liderar con prop\u00f3sito.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81f78aa elementor-widget elementor-widget-heading\" data-id=\"81f78aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Precio del programa<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-478c3ec elementor-widget elementor-widget-text-editor\" data-id=\"478c3ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">El MBA en Direcci\u00f3n y Gesti\u00f3n de Empresas de Salud, correspondiente a la edici\u00f3n de septiembre de 2026, se ofrece en dos modalidades con los siguientes importes de matr\u00edcula:<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Online Blended:<\/b><span style=\"font-weight: 400;\"> 9.500\u20ac<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Full Time\/Presencial:<\/b><span style=\"font-weight: 400;\"> 13.000\u20ac<\/span><\/li><\/ul><p><b>El importe incluye: <\/b><span style=\"font-weight: 400;\">Derechos acad\u00e9micos y material docente y titulaci\u00f3n por <\/span><b>UTAMED <\/b><span style=\"font-weight: 400;\">y acreditaci\u00f3n por <\/span><b>NUS Agency.<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53af03c elementor-widget elementor-widget-heading\" data-id=\"53af03c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Becas parciales\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-468187a elementor-widget elementor-widget-text-editor\" data-id=\"468187a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>NUS Agency<\/b><span style=\"font-weight: 400;\"> ofrece becas parciales dirigidas a perfiles con alto potencial:<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Becas al talento:<\/b><span style=\"font-weight: 400;\"> Para candidatos con nacionalidad europea que acrediten experiencia profesional, iniciativa emprendedora y visi\u00f3n innovadora.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Beca mujer directiva:<\/b><span style=\"font-weight: 400;\"> Para impulsar la carrera profesional de mujeres y su acceso a puestos de liderazgo.<\/span><\/li><\/ul><p><b>Nota:<\/b><span style=\"font-weight: 400;\"> Las becas son <\/span><b>parciales<\/b><span style=\"font-weight: 400;\"> y <\/span><b>compatibles entre s\u00ed<\/b><span style=\"font-weight: 400;\">, permitiendo incrementar el porcentaje total de ayuda.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b1d6cce\" data-id=\"b1d6cce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bb3ce69 elementor-widget elementor-widget-image\" data-id=\"bb3ce69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"516\" height=\"616\" src=\"https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/12\/master_mic_nus_agency_becas_2.webp\" class=\"attachment-large size-large wp-image-91958\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6e32cb2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6e32cb2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3e6d342\" data-id=\"3e6d342\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c4ab09 elementor-widget elementor-widget-heading\" data-id=\"4c4ab09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Formas de pago<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09b939d elementor-position-top elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"09b939d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/12\/mappinline.webp\" class=\"attachment-full size-full wp-image-91929\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Pago \u00fanico<\/h3><p class=\"elementor-image-box-description\">Descuento del 3% aplicable al formalizar la matr\u00edcula mediante transferencia directa a NUS Agency<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-01507bd elementor-position-top elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"01507bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/11\/health_it-black.webp\" class=\"attachment-full size-full wp-image-91761\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Pago fraccionado<\/h3><p class=\"elementor-image-box-description\">Sin intereses solo para residentes en Espa\u00f1a con Sabadell Consumer<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d4dfdec elementor-position-top elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"d4dfdec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/09\/Training.svg\" class=\"attachment-full size-full wp-image-90866\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-title\">Reserva de plaza<\/p><p class=\"elementor-image-box-description\">Con el abono inicial de la matr\u00edcula que ser\u00e1n 500 \u20ac<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f44fea9\" data-id=\"f44fea9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2c6bc77 elementor-widget elementor-widget-heading\" data-id=\"2c6bc77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Opciones de financiaci\u00f3n\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32ddeaa elementor-widget elementor-widget-text-editor\" data-id=\"32ddeaa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Invertir en tu futuro profesional es una decisi\u00f3n estrat\u00e9gica, por eso ofrecemos alternativas de financiaci\u00f3n flexibles para que puedas cursar el MBA sin frenar tus planes de crecimiento. Te acompa\u00f1amos para encontrar la opci\u00f3n que mejor se adapte a tu situaci\u00f3n para que te enfoques en avanzar, potenciar tu liderazgo y consolidar tu trayectoria directiva en el sector salud.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-faea973 elementor-widget elementor-widget-toggle\" data-id=\"faea973\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-2631\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2631\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Para residentes en Espa\u00f1a<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2631\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2631\"><ul><li><a href=\"https:\/\/www.caixabank.es\/personas\/financiacion\/prestamos-educacion_es.html\"><b>Caixabank<\/b><\/a><span style=\"font-weight: 400;\"> \u2013 <\/span><i><span style=\"font-weight: 400;\">Pr\u00e9stamo sin aval con diferentes modalidades<\/span><\/i><\/li><li><a href=\"https:\/\/www.santanderconsumer.es\/prestamos\/estudiantes.html\"><b>Banco Santander<\/b><\/a><\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h3 id=\"elementor-tab-title-2632\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2632\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><i class=\"fas fa-caret-right\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><i class=\"elementor-toggle-icon-opened fas fa-caret-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Para estudiantes no residentes en Espa\u00f1a<\/a>\n\t\t\t\t\t<\/h3>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2632\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2632\"><p><strong>Colombia<\/strong><br \/>Gestiona la financiaci\u00f3n desde tu pa\u00eds de origen y aprovecha el 3% de descuento por pago \u00fanico.<\/p><ul><li><a href=\"https:\/\/www.davivienda.com\/personas\/creditos\/credito-educativo\"><b>Banco Davivienda<\/b><\/a><\/li><li><a href=\"https:\/\/www.bancolombia.com\/personas\/creditos\/estudio\"><b>Banco Bancolombia<\/b><\/a><\/li><\/ul><p><strong>M\u00e9xico<\/strong><br \/>Gestiona la financiaci\u00f3n desde tu pa\u00eds de origen y aprovecha el 3% de descuento por pago \u00fanico.<\/p><ul><li><a href=\"https:\/\/www.bbva.mx\/personas\/productos\/creditos.html\"><b>Banco BBVA M\u00e9xico<\/b><\/a><\/li><li><a href=\"https:\/\/www.santander.com.mx\/personas\/creditos-personales.html\"><b>Banco Santander M\u00e9xico<\/b><\/a><\/li><\/ul><p><strong>Chile<\/strong><br \/>Gestiona la financiaci\u00f3n desde tu pa\u00eds de origen y aprovecha el 3% de descuento por pago \u00fanico.<\/p><ul><li><a href=\"https:\/\/sitiospublicos.bancochile.cl\/personas\/solvencia\/detalle\/credito-de-estudios\">Banco de Chile<\/a><\/li><li><a href=\"https:\/\/banco.santander.cl\/personas\/credito-de-consumo\">Banco Santander Chile<\/a><\/li><\/ul><p><strong>Costa Rica<\/strong><br \/>Gestiona la financiaci\u00f3n desde tu pa\u00eds de origen y aprovecha el 3% de descuento por pago \u00fanico.<\/p><ul><li><a href=\"https:\/\/www.bancopopular.fi.cr\/credito\/\">Banco Popular y de Desarrollo Comunal<\/a><\/li><li><a href=\"https:\/\/www.bncr.fi.cr\/solicitar-credito-bn-educacion\">Banco Nacional de Costa Rica (BNCR)<\/a><\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-41f9f6f elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"41f9f6f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-d01d76f elementor-hidden-tablet elementor-hidden-mobile\" data-id=\"d01d76f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c894bd0\" data-id=\"c894bd0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-72603bc elementor-widget elementor-widget-menu-anchor\" data-id=\"72603bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"form\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84f5158 elementor-widget elementor-widget-heading\" data-id=\"84f5158\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Elige NUS Agency y lidera en el sector salud<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-190bfd4 elementor-widget elementor-widget-shortcode\" data-id=\"190bfd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f91840-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"91840\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/masters-y-postgrados\/91913#wpcf7-f91840-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"91840\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f91840-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<p><label>Nombre *<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n<\/p>\n<p><label>Email *<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n<\/p>\n<p><label>Tel\u00e9fono *<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"phonete\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-phonetext wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-phonetext\" data-numberonly=\"true\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Tel\u00e9fono\" value=\"\" type=\"text\" name=\"phonete\" \/><input type=\"hidden\" name=\"phonete-country-code\" class=\"wpcf7-phonetext-country-code\" \/><\/span>\n<\/p>\n<p><label>Elige tu modalidad *<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"modalidad\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"modalidad\"><option value=\"\">&#8212;Por favor, elige una opci\u00f3n&#8212;<\/option><option value=\"MBA Full-Time en ingl\u00e9s\">MBA Full-Time en ingl\u00e9s<\/option><option value=\"MBA Online (Blended) en castellano\">MBA Online (Blended) en castellano<\/option><\/select><\/span>\n<\/p>\n<p><label>\u00bfCu\u00e1l es tu perfil? *<\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"perfil\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"perfil\"><option value=\"\">&#8212;Por favor, elige una opci\u00f3n&#8212;<\/option><option value=\"Sanitario \/ Salud\">Sanitario \/ Salud<\/option><option value=\"Empresarial \/ Negocios\">Empresarial \/ Negocios<\/option><option value=\"Legal \/ Regulaci\u00f3n\">Legal \/ Regulaci\u00f3n<\/option><option value=\"Ingenier\u00eda \/ Tecnolog\u00eda\">Ingenier\u00eda \/ Tecnolog\u00eda<\/option><option value=\"Econ\u00f3mico \/ Finanzas \/ Administraci\u00f3n\">Econ\u00f3mico \/ Finanzas \/ Administraci\u00f3n<\/option><option value=\"Arte \/ Cultura\">Arte \/ Cultura<\/option><option value=\"Educaci\u00f3n \/ Docencia\">Educaci\u00f3n \/ Docencia<\/option><option value=\"Otro\">Otro<\/option><\/select><\/span>\n<\/p>\n<div class=\"campo-politica\">\n\t<p><label for=\"acepto-politica\"><br \/>\n<input type=\"checkbox\" id=\"acepto-politica\" \/> He le\u00eddo y acepto la <a href=\"https:\/\/www.nus.agency\/politica-privacidad\" target=\"_blank\" rel=\"noopener\">Pol\u00edtica de privacidad<\/a><br \/>\n<\/label>\n\t<\/p>\n<\/div>\n<p class=\"info-legal\" style=\"font-size: 12px; margin-top: 5px;\"><br \/>\n<strong>Informaci\u00f3n sobre protecci\u00f3n de datos NUS Agency:<\/strong> Usamos tus datos para responder tus consultas y enviarte informaci\u00f3n comercial. Puedes ejercer tus derechos o retirar tu consentimiento escribiendo a <a href=\"mailto:in**@*us.agency\" data-original-string=\"BqNcprwlwvIEr7E4muZWZA==30f2V\/T6629Sxd+QpRbc1oUEQ==\" title=\"Este contacto ha sido codificado por Anti-Spam by CleanTalk. Haz clic para decodificar. Para finalizar la decodificaci\u00f3n, aseg\u00farate de que JavaScript est\u00e1 activado en tu navegador.\"><span \n                data-original-string='uXXMmShFXdWa+oRp36kIiQ==30fGIZWuqT8ZCEm+21kJjp94Q=='\n                class='apbct-email-encoder'\n                title='Este contacto ha sido codificado por Anti-Spam by CleanTalk. Haz clic para decodificar. Para finalizar la decodificaci\u00f3n, aseg\u00farate de que JavaScript est\u00e1 activado en tu navegador.'>in<span class=\"apbct-blur\">**<\/span>@<span class=\"apbct-blur\">*<\/span>us.agency<\/span><\/a>.\n<\/p>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"utm_source\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"utm_medium\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"utm_campaign\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"utm_content\" \/>\n<input class=\"wpcf7-form-control wpcf7-hidden\" id=\"zc_gclid\" value=\"\" type=\"hidden\" name=\"zc_gclid\" \/>\n<div class=\"boton-contenedor\">\n\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Solicita informaci\u00f3n\" \/>\n\t<\/p>\n<\/div><input type=\"hidden\" id=\"ct_checkjs_cf7_ac627ab1ccbdb62ec96e702f07f6425b\" name=\"ct_checkjs_cf7\" value=\"0\" \/><script >setTimeout(function(){var ct_input_name = \"ct_checkjs_cf7_ac627ab1ccbdb62ec96e702f07f6425b\";if (document.getElementById(ct_input_name) !== null) {var ct_input_value = document.getElementById(ct_input_name).value;document.getElementById(ct_input_name).value = document.getElementById(ct_input_name).value.replace(ct_input_value, '245469608');}}, 1000);<\/script><input\n                    class=\"apbct_special_field apbct_email_id__wp_contact_form_7\"\n                    name=\"apbct__email_id__wp_contact_form_7\"\n                    aria-label=\"Formulario de contacto\"\n                    type=\"text\" size=\"30\" maxlength=\"200\" autocomplete=\"off\"\n                    value=\"\"\n                \/><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input\n                    class=\"apbct_special_field apbct_email_id__elementor_form\"\n                    name=\"apbct__email_id__elementor_form\"\n                    aria-label=\"Formulario de contacto\"\n                    type=\"text\" size=\"30\" maxlength=\"200\" autocomplete=\"off\"\n                    value=\"\"\n                \/><\/form>\n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-ca1230c elementor-hidden-tablet elementor-hidden-mobile\" data-id=\"ca1230c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9b7869b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9b7869b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9ad5d89\" data-id=\"9ad5d89\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab5084b elementor-widget elementor-widget-image\" data-id=\"ab5084b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"213\" src=\"https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/11\/Diploma-UTAMED-Master.png\" class=\"attachment-medium size-medium wp-image-96039\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e80ca0 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"0e80ca0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>T\u00edtulo propio universitario<\/strong><\/p><p><span style=\"font-weight: 400;\">Al completar el programa recibir\u00e1s una titulaci\u00f3n propia expedida por la Universidad Tecnol\u00f3gica Atl\u00e1ntico-Mediterr\u00e1neo (UTAMED).<\/span><\/p><p><span style=\"font-weight: 400;\">Este t\u00edtulo certifica que has superado satisfactoriamente el programa formativo y cuenta con el respaldo de una instituci\u00f3n universitaria oficialmente reconocida dentro del sistema educativo espa\u00f1ol.<\/span><\/p><h4><span style=\"color: #000000;\">*Este es un ejemplo del t\u00edtulo propio de formaci\u00f3n permanente que recibir\u00e1s<\/span><\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-acbb917\" data-id=\"acbb917\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c21d218 elementor-widget elementor-widget-image\" data-id=\"c21d218\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"213\" src=\"https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/11\/Logo-Educacion-Superior-Europea.png\" class=\"attachment-medium size-medium wp-image-96041\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d97261 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"0d97261\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Universidad oficial<\/strong><\/p><p><span style=\"font-weight: 400;\">La Universidad Tecnol\u00f3gica Atl\u00e1ntico\u2011Mediterr\u00e1neo (UTAMED) es una universidad privada reconocida oficialmente por el Estado espa\u00f1ol, seg\u00fan la <\/span><span style=\"text-decoration: underline; color: #99ccff;\"><a style=\"color: #99ccff;\" href=\"https:\/\/www.boe.es\/diario_boe\/txt.php?id=BOE-A-2023-21668\"><span style=\"font-weight: 400;\">Ley 11\/2023, de 3 de octubre, publicada en el Bolet\u00edn Oficial del Estado (BOE).<\/span><\/a><\/span><\/p><p><span style=\"font-weight: 400;\">Esta ley reconoce oficialmente a la universidad dentro del sistema universitario espa\u00f1ol y garantiza que cumple con los requisitos legales para impartir formaci\u00f3n universitaria.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"featured_media":91945,"template":"","meta":[],"tags":[1400,1402,1401],"class_list":["post-91913","masters-y-postgrados","type-masters-y-postgrados","status-publish","has-post-thumbnail","hentry","tag-mba","tag-mba-en-salud","tag-mba-sanitario"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.9 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>MBA en Direcci\u00f3n y Gesti\u00f3n de Empresas de Salud - NUS Agency<\/title>\n<meta name=\"description\" content=\"MBA l\u00edder en gesti\u00f3n sanitaria con enfoque internacional, innovador y pr\u00e1ctico. Modalidades Full-Time y Blended, y experiencia internacional en Barcelona.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nus.agency\/es\/masters-y-postgrados\/mba-direccion-gestion-empresas-salud\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MBA en Direcci\u00f3n y Gesti\u00f3n de Empresas de Salud\" \/>\n<meta property=\"og:description\" content=\"MBA l\u00edder en gesti\u00f3n sanitaria con enfoque internacional, innovador y pr\u00e1ctico. Modalidades Full-Time y Blended, y experiencia internacional en Barcelona.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nus.agency\/es\/masters-y-postgrados\/mba-direccion-gestion-empresas-salud\" \/>\n<meta property=\"og:site_name\" content=\"NUS Agency\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nus.Agency\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-23T15:11:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/12\/master_mba_nus_agency_blended.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1376\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@NusUnidad\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"15 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"MedicalWebPage\"],\"@id\":\"https:\\\/\\\/www.nus.agency\\\/es\\\/masters-y-postgrados\\\/mba-direccion-gestion-empresas-salud\",\"url\":\"https:\\\/\\\/www.nus.agency\\\/es\\\/masters-y-postgrados\\\/mba-direccion-gestion-empresas-salud\",\"name\":\"MBA en Direcci\u00f3n y Gesti\u00f3n de Empresas de Salud - NUS Agency\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nus.agency\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.nus.agency\\\/es\\\/masters-y-postgrados\\\/mba-direccion-gestion-empresas-salud#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nus.agency\\\/es\\\/masters-y-postgrados\\\/mba-direccion-gestion-empresas-salud#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nus.agency\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/master_mba_nus_agency_blended.webp\",\"datePublished\":\"2025-12-19T10:10:22+00:00\",\"dateModified\":\"2026-03-23T15:11:41+00:00\",\"description\":\"MBA l\u00edder en gesti\u00f3n sanitaria con enfoque internacional, innovador y pr\u00e1ctico. Modalidades Full-Time y Blended, y experiencia internacional en Barcelona.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.nus.agency\\\/es\\\/masters-y-postgrados\\\/mba-direccion-gestion-empresas-salud#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.nus.agency\\\/es\\\/masters-y-postgrados\\\/mba-direccion-gestion-empresas-salud\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.nus.agency\\\/es\\\/masters-y-postgrados\\\/mba-direccion-gestion-empresas-salud#primaryimage\",\"url\":\"https:\\\/\\\/www.nus.agency\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/master_mba_nus_agency_blended.webp\",\"contentUrl\":\"https:\\\/\\\/www.nus.agency\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/master_mba_nus_agency_blended.webp\",\"width\":1376,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.nus.agency\\\/es\\\/masters-y-postgrados\\\/mba-direccion-gestion-empresas-salud#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.nus.agency\\\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MBA en Direcci\u00f3n y Gesti\u00f3n de Empresas de Salud\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nus.agency\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.nus.agency\\\/es\\\/\",\"name\":\"NUS Agency\",\"description\":\"Formaci\u00f3n especializada en el sector salud y bienestar. M\u00e1ster en Enfermer\u00eda Dermoest\u00e9tica, Fisioest\u00e9tica, Neurom\u00fasica, Terapia Breve.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.nus.agency\\\/es\\\/#organization\"},\"alternateName\":\"nus.agency\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.nus.agency\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.nus.agency\\\/es\\\/#organization\",\"name\":\"Nus Agency\",\"alternateName\":\"nus.agency\",\"url\":\"https:\\\/\\\/www.nus.agency\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.nus.agency\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.nus.agency\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/LOGO-NUS.png\",\"contentUrl\":\"https:\\\/\\\/www.nus.agency\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/LOGO-NUS.png\",\"width\":500,\"height\":500,\"caption\":\"Nus Agency\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nus.agency\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nus.Agency\",\"https:\\\/\\\/x.com\\\/NusUnidad\",\"https:\\\/\\\/www.instagram.com\\\/nus.agency\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/nus-agency\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCcseK4CACJLLFX6J19Om5qQ\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"MBA en Direcci\u00f3n y Gesti\u00f3n de Empresas de Salud - NUS Agency","description":"MBA l\u00edder en gesti\u00f3n sanitaria con enfoque internacional, innovador y pr\u00e1ctico. Modalidades Full-Time y Blended, y experiencia internacional en Barcelona.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nus.agency\/es\/masters-y-postgrados\/mba-direccion-gestion-empresas-salud","og_locale":"es_ES","og_type":"article","og_title":"MBA en Direcci\u00f3n y Gesti\u00f3n de Empresas de Salud","og_description":"MBA l\u00edder en gesti\u00f3n sanitaria con enfoque internacional, innovador y pr\u00e1ctico. Modalidades Full-Time y Blended, y experiencia internacional en Barcelona.","og_url":"https:\/\/www.nus.agency\/es\/masters-y-postgrados\/mba-direccion-gestion-empresas-salud","og_site_name":"NUS Agency","article_publisher":"https:\/\/www.facebook.com\/Nus.Agency","article_modified_time":"2026-03-23T15:11:41+00:00","og_image":[{"width":1376,"height":768,"url":"https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/12\/master_mba_nus_agency_blended.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@NusUnidad","twitter_misc":{"Tiempo de lectura":"15 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","MedicalWebPage"],"@id":"https:\/\/www.nus.agency\/es\/masters-y-postgrados\/mba-direccion-gestion-empresas-salud","url":"https:\/\/www.nus.agency\/es\/masters-y-postgrados\/mba-direccion-gestion-empresas-salud","name":"MBA en Direcci\u00f3n y Gesti\u00f3n de Empresas de Salud - NUS Agency","isPartOf":{"@id":"https:\/\/www.nus.agency\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.nus.agency\/es\/masters-y-postgrados\/mba-direccion-gestion-empresas-salud#primaryimage"},"image":{"@id":"https:\/\/www.nus.agency\/es\/masters-y-postgrados\/mba-direccion-gestion-empresas-salud#primaryimage"},"thumbnailUrl":"https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/12\/master_mba_nus_agency_blended.webp","datePublished":"2025-12-19T10:10:22+00:00","dateModified":"2026-03-23T15:11:41+00:00","description":"MBA l\u00edder en gesti\u00f3n sanitaria con enfoque internacional, innovador y pr\u00e1ctico. Modalidades Full-Time y Blended, y experiencia internacional en Barcelona.","breadcrumb":{"@id":"https:\/\/www.nus.agency\/es\/masters-y-postgrados\/mba-direccion-gestion-empresas-salud#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nus.agency\/es\/masters-y-postgrados\/mba-direccion-gestion-empresas-salud"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.nus.agency\/es\/masters-y-postgrados\/mba-direccion-gestion-empresas-salud#primaryimage","url":"https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/12\/master_mba_nus_agency_blended.webp","contentUrl":"https:\/\/www.nus.agency\/wp-content\/uploads\/2025\/12\/master_mba_nus_agency_blended.webp","width":1376,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/www.nus.agency\/es\/masters-y-postgrados\/mba-direccion-gestion-empresas-salud#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.nus.agency\/es"},{"@type":"ListItem","position":2,"name":"MBA en Direcci\u00f3n y Gesti\u00f3n de Empresas de Salud"}]},{"@type":"WebSite","@id":"https:\/\/www.nus.agency\/es\/#website","url":"https:\/\/www.nus.agency\/es\/","name":"NUS Agency","description":"Formaci\u00f3n especializada en el sector salud y bienestar. M\u00e1ster en Enfermer\u00eda Dermoest\u00e9tica, Fisioest\u00e9tica, Neurom\u00fasica, Terapia Breve.","publisher":{"@id":"https:\/\/www.nus.agency\/es\/#organization"},"alternateName":"nus.agency","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nus.agency\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.nus.agency\/es\/#organization","name":"Nus Agency","alternateName":"nus.agency","url":"https:\/\/www.nus.agency\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.nus.agency\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.nus.agency\/wp-content\/uploads\/2023\/09\/LOGO-NUS.png","contentUrl":"https:\/\/www.nus.agency\/wp-content\/uploads\/2023\/09\/LOGO-NUS.png","width":500,"height":500,"caption":"Nus Agency"},"image":{"@id":"https:\/\/www.nus.agency\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Nus.Agency","https:\/\/x.com\/NusUnidad","https:\/\/www.instagram.com\/nus.agency\/","https:\/\/www.linkedin.com\/school\/nus-agency\/","https:\/\/www.youtube.com\/channel\/UCcseK4CACJLLFX6J19Om5qQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.nus.agency\/es\/wp-json\/wp\/v2\/masters-y-postgrados\/91913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nus.agency\/es\/wp-json\/wp\/v2\/masters-y-postgrados"}],"about":[{"href":"https:\/\/www.nus.agency\/es\/wp-json\/wp\/v2\/types\/masters-y-postgrados"}],"version-history":[{"count":94,"href":"https:\/\/www.nus.agency\/es\/wp-json\/wp\/v2\/masters-y-postgrados\/91913\/revisions"}],"predecessor-version":[{"id":96122,"href":"https:\/\/www.nus.agency\/es\/wp-json\/wp\/v2\/masters-y-postgrados\/91913\/revisions\/96122"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nus.agency\/es\/wp-json\/wp\/v2\/media\/91945"}],"wp:attachment":[{"href":"https:\/\/www.nus.agency\/es\/wp-json\/wp\/v2\/media?parent=91913"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nus.agency\/es\/wp-json\/wp\/v2\/tags?post=91913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}